{"id":402,"date":"2017-02-17T15:11:48","date_gmt":"2017-02-17T14:11:48","guid":{"rendered":"http:\/\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg"},"modified":"2017-02-17T15:11:48","modified_gmt":"2017-02-17T14:11:48","slug":"nutella-flip-flops-for-ferrero","status":"inherit","type":"attachment","link":"https:\/\/clpremium.fr\/index.php\/portfolio\/371\/nutella-flip-flops-for-ferrero\/","title":{"rendered":"nutella-flip-flops-for-ferrero"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?ssl=1'><img width=\"300\" height=\"300\" src=\"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?w=800 800w, https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=150%2C150 150w, https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=300%2C300 300w, https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=768%2C768 768w, https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=220%2C220 220w, https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=50%2C50 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"402\" data-permalink=\"https:\/\/clpremium.fr\/index.php\/portfolio\/371\/nutella-flip-flops-for-ferrero\/\" data-orig-file=\"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=800%2C800&amp;ssl=1\" data-orig-size=\"800,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"nutella-flip-flops-for-ferrero\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=300%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=800%2C800&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":800,"file":"2017\/02\/nutella-flip-flops-for-ferrero.jpg","sizes":{"thumbnail":{"file":"nutella-flip-flops-for-ferrero-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"nutella-flip-flops-for-ferrero-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=300%2C300&ssl=1"},"medium_large":{"file":"nutella-flip-flops-for-ferrero-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero-768x768.jpg"},"blask-site-logo":{"file":"nutella-flip-flops-for-ferrero-220x220.jpg","width":220,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=220%2C220&ssl=1"},"jetpack-portfolio-admin-thumb":{"file":"nutella-flip-flops-for-ferrero-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?resize=50%2C50&ssl=1"},"full":{"file":"nutella-flip-flops-for-ferrero.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/i1.wp.com\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg?fit=800%2C800&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":371,"source_url":"https:\/\/clpremium.fr\/wp-content\/uploads\/2017\/02\/nutella-flip-flops-for-ferrero.jpg","_links":{"self":[{"href":"https:\/\/clpremium.fr\/index.php\/wp-json\/wp\/v2\/media\/402"}],"collection":[{"href":"https:\/\/clpremium.fr\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/clpremium.fr\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/clpremium.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}]}}